{"id":22041,"date":"2017-02-01T11:28:00","date_gmt":"2017-02-01T16:28:00","guid":{"rendered":"http:\/\/52.229.127.56\/?p=22041\/"},"modified":"2021-02-17T10:48:08","modified_gmt":"2021-02-17T15:48:08","slug":"ameliorer-les-soins-grace-a-limpression-3d","status":"publish","type":"post","link":"https:\/\/www.ottawahospital.on.ca\/fr\/non-classifiee\/ameliorer-les-soins-grace-a-limpression-3d\/","title":{"rendered":"Am\u00e9liorer les soins gr\u00e2ce \u00e0 l\u2019impression 3D"},"content":{"rendered":"<p class=\"text-center\">Le D<sup>r&nbsp;<\/sup>Adnan&nbsp;Sheikh tient la r\u00e9plique exacte du pelvis d\u2019un patient dont une hanche est grug\u00e9e par le cancer. Cette r\u00e9plique a \u00e9t\u00e9 faite par une imprimante 3D.<\/p>\n<p>Con\u00e7ue \u00e0 partir d\u2019une tomodensitom\u00e9trie (examen d\u2019imagerie m\u00e9dicale), elle a \u00e9t\u00e9 un outil essentiel \u00e0 la planification de la complexe chirurgie de remplacement de la hanche. Voir l\u2019\u00e9tendue des dommages faits par la maladie a donn\u00e9 aux chirurgiens une id\u00e9e claire de la fa\u00e7on d\u2019op\u00e9rer. Sans la r\u00e9plique, ils n\u2019auraient pas eu autant de d\u00e9tails avant la chirurgie.<\/p>\n<p>\u00ab&nbsp;L\u2019impression 3D est en train de r\u00e9volutionner la fa\u00e7on de pratiquer la m\u00e9decine \u00e0 L\u2019H\u00f4pital d\u2019Ottawa&nbsp;\u00bb, affirme le D<sup>r<\/sup>&nbsp;Adnan&nbsp;Sheikh, directeur m\u00e9dical du programme d\u2019impression 3D de l\u2019H\u00f4pital.<\/p>\n<p>R\u00e9volutionner est le mot juste. Une imprimante 3D ajoute successivement de minces couches de mat\u00e9riel pour cr\u00e9er un objet solide en trois dimensions.<\/p>\n<p>Gr\u00e2ce \u00e0 la g\u00e9n\u00e9rosit\u00e9 d\u2019un donateur, l\u2019H\u00f4pital a achet\u00e9 une imprimante 3D qui utilise de l\u2019acrylique et du plastique pour imprimer des objets comme un pelvis endommag\u00e9.<\/p>\n<p>\u00ab&nbsp;Nous imprimerons des mod\u00e8les \u00e0 des fins chirurgicales et d\u2019enseignement&nbsp;\u00bb, pr\u00e9cise le D<sup>r&nbsp;<\/sup>Frank&nbsp;Rybicki, chef de l\u2019Imagerie m\u00e9dicale \u00e0 l\u2019H\u00f4pital. \u00ab&nbsp;Si une personne a le cancer, nous pourrons imprimer l\u2019organe touch\u00e9 pour le lui montrer et lui expliquer le plan de traitement.&nbsp;\u00bb<\/p>\n<p>D\u00e9terminer d\u2019avance avec pr\u00e9cision la fa\u00e7on d\u2019op\u00e9rer r\u00e9duit la dur\u00e9e de la chirurgie, bien souvent de quelques heures, ce qui permet de r\u00e9aliser des \u00e9conomies consid\u00e9rables. R\u00e9duire la dur\u00e9e des chirurgies fait aussi diminuer les temps d\u2019attente et permet par le fait m\u00eame de traiter plus de patients.<\/p>\n<p>\u00ab&nbsp;Nous pouvons offrir les soins d\u2019une fa\u00e7on qui n\u2019\u00e9tait pas \u00e0 notre port\u00e9e avant l\u2019arriv\u00e9e de cet outil&nbsp;\u00bb, ajoute le D<sup>r&nbsp;<\/sup>Rybicki.<\/p>\n<p>L\u2019H\u00f4pital d\u2019Ottawa est le premier h\u00f4pital au Canada \u00e0 int\u00e9grer un programme d\u2019impression m\u00e9dicale 3D \u00e0 ses activit\u00e9s de planification chirurgicale, d\u2019enseignement et de recherche. Ce programme sera utile en cas de cancer, de fracture, de probl\u00e8mes orthop\u00e9diques et vasculaires et de tumeurs au cerveau. Il ouvrira aussi de nouvelles perspectives en recherche.<\/p>\n<p>L\u2019impression 3D est une innovation extraordinaire qui aidera les patients aujourd\u2019hui et dans l\u2019avenir. L\u2019H\u00f4pital pr\u00e9voit \u00e9largir son programme dans les prochaines ann\u00e9es pour inclure des imprimantes 3D capables d\u2019imprimer des tissus, des os et des organes humains en vue de les implanter chez des patients.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Dr&nbsp;Adnan&nbsp;Sheikh tient la r\u00e9plique exacte du pelvis d\u2019un patient dont une hanche est grug\u00e9e par le cancer. Cette r\u00e9plique a \u00e9t\u00e9 faite par une imprimante 3D. Con\u00e7ue \u00e0 partir d\u2019une tomodensitom\u00e9trie (examen d\u2019imagerie m\u00e9dicale), elle a \u00e9t\u00e9 un outil essentiel \u00e0 la planification de la complexe chirurgie de remplacement de la hanche. Voir l\u2019\u00e9tendue [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":22039,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-22041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.ottawahospital.on.ca\/fr\/wp-json\/wp\/v2\/posts\/22041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ottawahospital.on.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ottawahospital.on.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ottawahospital.on.ca\/fr\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ottawahospital.on.ca\/fr\/wp-json\/wp\/v2\/comments?post=22041"}],"version-history":[{"count":0,"href":"https:\/\/www.ottawahospital.on.ca\/fr\/wp-json\/wp\/v2\/posts\/22041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ottawahospital.on.ca\/fr\/wp-json\/wp\/v2\/media\/22039"}],"wp:attachment":[{"href":"https:\/\/www.ottawahospital.on.ca\/fr\/wp-json\/wp\/v2\/media?parent=22041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ottawahospital.on.ca\/fr\/wp-json\/wp\/v2\/categories?post=22041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ottawahospital.on.ca\/fr\/wp-json\/wp\/v2\/tags?post=22041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}